{"id":7167,"date":"2025-03-05T11:50:01","date_gmt":"2025-03-05T11:50:01","guid":{"rendered":"https:\/\/stadt-brandis.de\/?p=3195"},"modified":"2025-03-05T11:50:01","modified_gmt":"2025-03-05T11:50:01","slug":"buergersprechstunde-online-3","status":"publish","type":"post","link":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/2025\/03\/05\/buergersprechstunde-online-3\/","title":{"rendered":"B\u00fcrgersprechstunde online"},"content":{"rendered":"<p class=\"wp-block-paragraph\">B\u00fcrgermeister Arno Jesse stellt sich in der Online-B\u00fcrgersprechstunde wieder den Fragen der Zuschauer. \u00dcber <a href=\"https:\/\/youtu.be\/j6yu201QlLE\">diesen Link<\/a> gelangen Sie zur vergangenen Sprechstunde vom 04.03.2025. Themen waren Windenergie, Gr\u00fcner Ring Leipzig, Gefl\u00fcgelpest, F\u00f6rdermittel f\u00fcr die Innenstadt, Vorhaben f\u00fcr 2025 und die kommunale Finanzlage, Neub\u00fcrgertreffen, Oberschule Brandis sowie die Gesundheitsversorgung &#8211; Muldentalklinik. Sie haben eine Frage? Schicken Sie diese gern an <a href=\"mailto:buergerdialog@muldental.tv\">buergerdialog@muldental.tv<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>B\u00fcrgermeister Arno Jesse stellt sich in der Online-B\u00fcrgersprechstunde wieder den Fragen der Zuschauer. \u00dcber diesen Link gelangen Sie zur vergangenen Sprechstunde vom 04.03.2025. Themen waren Windenergie, Gr\u00fcner Ring Leipzig, Gefl\u00fcgelpest, F\u00f6rdermittel f\u00fcr die Innenstadt, Vorhaben f\u00fcr 2025 und die kommunale Finanzlage, Neub\u00fcrgertreffen, Oberschule Brandis sowie die Gesundheitsversorgung &#8211; Muldentalklinik. Sie haben eine Frage? Schicken Sie diese gern an buergerdialog@muldental.tv.<\/p>","protected":false},"author":9,"featured_media":7168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[43],"tags":[],"class_list":["post-7167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00fcrgersprechstunde online - Brandis - Virtuelles Rathaus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rathaus.stadt-brandis.de\/de_informal\/2025\/03\/05\/buergersprechstunde-online-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00fcrgersprechstunde online - Brandis - Virtuelles Rathaus\" \/>\n<meta property=\"og:description\" content=\"B\u00fcrgermeister Arno Jesse stellt sich in der Online-B\u00fcrgersprechstunde wieder den Fragen der Zuschauer. \u00dcber diesen Link gelangen Sie zur vergangenen Sprechstunde vom 04.03.2025. Themen waren Windenergie, Gr\u00fcner Ring Leipzig, Gefl\u00fcgelpest, F\u00f6rdermittel f\u00fcr die Innenstadt, Vorhaben f\u00fcr 2025 und die kommunale Finanzlage, Neub\u00fcrgertreffen, Oberschule Brandis sowie die Gesundheitsversorgung &#8211; Muldentalklinik. Sie haben eine Frage? Schicken Sie diese gern an buergerdialog@muldental.tv.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rathaus.stadt-brandis.de\/de_informal\/2025\/03\/05\/buergersprechstunde-online-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Brandis - Virtuelles Rathaus\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T11:50:01+00:00\" \/>\n<meta name=\"author\" content=\"postsync\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"postsync\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/\"},\"author\":{\"name\":\"postsync\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/#\/schema\/person\/b6680492f15a38ccc9dfa24f63937a1e\"},\"headline\":\"B\u00fcrgersprechstunde online\",\"datePublished\":\"2025-03-05T11:50:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/\"},\"wordCount\":70,\"commentCount\":3,\"image\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de-leichte-sprache\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/\",\"url\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/\",\"name\":\"B\u00fcrgersprechstunde online - Brandis - Virtuelles Rathaus\",\"isPartOf\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg\",\"datePublished\":\"2025-03-05T11:50:01+00:00\",\"author\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/#\/schema\/person\/b6680492f15a38ccc9dfa24f63937a1e\"},\"breadcrumb\":{\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#breadcrumb\"},\"inLanguage\":\"de-leichte-sprache\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-leichte-sprache\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage\",\"url\":\"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg\",\"contentUrl\":\"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rathaus.stadt-brandis.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00fcrgersprechstunde online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/#website\",\"url\":\"https:\/\/rathaus.stadt-brandis.de\/\",\"name\":\"Brandis - Virtuelles Rathaus\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rathaus.stadt-brandis.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-leichte-sprache\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/rathaus.stadt-brandis.de\/#\/schema\/person\/b6680492f15a38ccc9dfa24f63937a1e\",\"name\":\"postsync\",\"url\":\"https:\/\/rathaus.stadt-brandis.de\/de_informal\/author\/postsync\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00fcrgersprechstunde online - Brandis - Virtuelles Rathaus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/2025\/03\/05\/buergersprechstunde-online-3\/","og_locale":"de_DE","og_type":"article","og_title":"B\u00fcrgersprechstunde online - Brandis - Virtuelles Rathaus","og_description":"B\u00fcrgermeister Arno Jesse stellt sich in der Online-B\u00fcrgersprechstunde wieder den Fragen der Zuschauer. \u00dcber diesen Link gelangen Sie zur vergangenen Sprechstunde vom 04.03.2025. Themen waren Windenergie, Gr\u00fcner Ring Leipzig, Gefl\u00fcgelpest, F\u00f6rdermittel f\u00fcr die Innenstadt, Vorhaben f\u00fcr 2025 und die kommunale Finanzlage, Neub\u00fcrgertreffen, Oberschule Brandis sowie die Gesundheitsversorgung &#8211; Muldentalklinik. Sie haben eine Frage? Schicken Sie diese gern an buergerdialog@muldental.tv.","og_url":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/2025\/03\/05\/buergersprechstunde-online-3\/","og_site_name":"Brandis - Virtuelles Rathaus","article_published_time":"2025-03-05T11:50:01+00:00","author":"postsync","twitter_card":"summary_large_image","twitter_misc":{"Written by":"postsync"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#article","isPartOf":{"@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/"},"author":{"name":"postsync","@id":"https:\/\/rathaus.stadt-brandis.de\/#\/schema\/person\/b6680492f15a38ccc9dfa24f63937a1e"},"headline":"B\u00fcrgersprechstunde online","datePublished":"2025-03-05T11:50:01+00:00","mainEntityOfPage":{"@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/"},"wordCount":70,"commentCount":3,"image":{"@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage"},"thumbnailUrl":"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg","articleSection":["Aktuelles"],"inLanguage":"de-leichte-sprache","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/","url":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/","name":"B\u00fcrgersprechstunde online - Brandis - Virtuelles Rathaus","isPartOf":{"@id":"https:\/\/rathaus.stadt-brandis.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage"},"image":{"@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage"},"thumbnailUrl":"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg","datePublished":"2025-03-05T11:50:01+00:00","author":{"@id":"https:\/\/rathaus.stadt-brandis.de\/#\/schema\/person\/b6680492f15a38ccc9dfa24f63937a1e"},"breadcrumb":{"@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#breadcrumb"},"inLanguage":"de-leichte-sprache","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/"]}]},{"@type":"ImageObject","inLanguage":"de-leichte-sprache","@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#primaryimage","url":"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg","contentUrl":"https:\/\/rathaus.stadt-brandis.de\/wp-content\/uploads\/2025\/03\/BSST_Brandis_Thumbnail.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/rathaus.stadt-brandis.de\/2025\/03\/05\/buergersprechstunde-online-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rathaus.stadt-brandis.de\/"},{"@type":"ListItem","position":2,"name":"B\u00fcrgersprechstunde online"}]},{"@type":"WebSite","@id":"https:\/\/rathaus.stadt-brandis.de\/#website","url":"https:\/\/rathaus.stadt-brandis.de\/","name":"Brandis - Virtuelles Rathaus","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rathaus.stadt-brandis.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-leichte-sprache"},{"@type":"Person","@id":"https:\/\/rathaus.stadt-brandis.de\/#\/schema\/person\/b6680492f15a38ccc9dfa24f63937a1e","name":"postsync","url":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/author\/postsync\/"}]}},"_links":{"self":[{"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/posts\/7167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/comments?post=7167"}],"version-history":[{"count":0,"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/posts\/7167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/media\/7168"}],"wp:attachment":[{"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/media?parent=7167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/categories?post=7167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rathaus.stadt-brandis.de\/de_informal\/wp-json\/wp\/v2\/tags?post=7167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}